{"id":2813,"date":"2022-05-23T12:01:40","date_gmt":"2022-05-23T10:01:40","guid":{"rendered":"https:\/\/www.tqs-group.com\/selezione-automatica-dei-pezzi-per-il-settore-dellorologeria\/"},"modified":"2023-02-14T12:20:58","modified_gmt":"2023-02-14T11:20:58","slug":"selezione-automatica-pezzi-settore-orologeria","status":"publish","type":"page","link":"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/","title":{"rendered":"Selezione automatica dei pezzi per il settore dell&#8217;orologeria"},"content":{"rendered":"<p>[vc_row][vc_column][vc_btn title=&#8221;Indietro&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#f7941f&#8221; custom_text=&#8221;#ffffff&#8221; shape=&#8221;round&#8221; size=&#8221;xs&#8221; align=&#8221;left&#8221; i_icon_fontawesome=&#8221;fas fa-arrow-left&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.tqs-group.com%2Fit%2Fselezione-automatica-dei-pezzi%2F&#8221; el_class=&#8221;btn-orange-white&#8221;][vc_column_text]Il <strong class=\"d2b\">settore dell&#8217;orologeria<\/strong> \u00e8 composto da attori molto diversi tra loro che si rivolgono a target di mercato differenti. Nel <strong class=\"d2b\">settore dell&#8217;orologeria<\/strong>, la <strong class=\"d2b\">selezione automatica<\/strong> si rivolge principalmente ai <strong class=\"d2b\">produttori di grandi serie di lusso<\/strong>. In effetti, l&#8217;automazione degli assemblaggi \u00e8 uno dei criteri in termini di necessit\u00e0 di controllo, ma non solo. I <strong>pezzi per l&#8217;orologeria<\/strong> sono estremamente piccoli e molto precisi, il che rende complicato il controllo manuale, soprattutto quando \u00e8 necessario controllare un numero elevato di pezzi. Ecco perch\u00e9 offriamo <a href=\"https:\/\/www.tqs-group.com\/it\/macchina-per-il-controllo-qualita-dei-pezzi-per-orologeria\/\">soluzioni robotizzate adatte a questo tipo di selezione<\/a>.[\/vc_column_text][vc_btn title=&#8221;Contattaci!&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#f7941f&#8221; custom_text=&#8221;#ffffff&#8221; shape=&#8221;round&#8221; align=&#8221;center&#8221; link=&#8221;url:https%3A%2F%2Fwww.tqs-group.com%2Fit%2Fcontatti%2F|title:Contatti&#8221; el_class=&#8221;btn-orange-white&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=&#8221;tres-gros-titre txt-orange&#8221;]<\/p>\n<h2>Esempio di selezione automatica di pezzi per il settore dell&#8217;orologeria<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;border-radius-machine-tri range-vente-machine range-vente-machine-right block-invert&#8221; css=&#8221;.vc_custom_1662972336611{background-image: url(https:\/\/www.tqs-group.com\/wp-content\/uploads\/2022\/05\/degrade.jpg?id=449) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;txt-align-left-mobile&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<span class=\"txt-orange\">Tipo di pezzo:<\/span> Piedino a vite[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Processo di produzione:<\/span> Tornitura[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Materiale: <\/span> Acciaio[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Rischi in caso di difetti:<\/span><\/p>\n<ul>\n<li>Impossibilit\u00e0 di montaggio<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_raw_html]PHRhYmxlPgogICAKICAgIDx0Ym9keT4KICAgICAgICA8dHI+CiAgICAgICAgICAgIDx0ZD5DUklURVJJIERJIFNFTEVaSU9ORTwvdGQ+CiAgICAgICAgICAgIDx0ZD5URUNOT0xPR0lBIFVUSUxJWlpBVEE8L3RkPgogICAgICAgIDwvdHI+CiAgICAgIDx0cj4KICAgICAgICAgICAgPHRkPkRpbWVuc2lvbmk8L3RkPgogICAgICAgICAgICA8dGQ+VmlzaW9uZSBhcnRpZmljaWFsZTwvdGQ+CiAgICAgICAgPC90cj4KICAgICAgPHRyPgogICAgICAgICAgICA8dGQ+Q2F0ZWdvcmlhIGRhIDLCtW08L3RkPgogICAgICAgICAgICA8dGQ+VmlzaW9uZSBhcnRpZmljaWFsZTwvdGQ+CiAgICAgICAgPC90cj4KICAgICAgPHRyPgogICAgICAgICAgICA8dGQ+QXNzZW56YSBkaSB0cnVjaW9saTwvdGQ+CiAgICAgICAgICAgIDx0ZD5WaXNpb25lIGFydGlmaWNpYWxlPC90ZD4KICAgICAgICA8L3RyPgogICAgICAgIDx0cj4KICAgICAgICAgICAgPHRkPkR1cmV6emE8L3RkPgogICAgICAgICAgICA8dGQ+Q29ycmVudGkgaW5kb3R0ZTwvdGQ+CiAgICAgICAgPC90cj4KICAgIDwvdGJvZHk+CjwvdGFibGU+[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1923&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row el_class=&#8221;border-radius-machine-tri range-vente-machine range-vente-machine-left&#8221; css=&#8221;.vc_custom_1662972292138{background-image: url(https:\/\/www.tqs-group.com\/wp-content\/uploads\/2022\/05\/offre-pour-idustriel-installe.jpg?id=454) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1921&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<span class=\"txt-orange\">Tipo di pezzo:<\/span> Ruota dentata[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Processo di produzione:<\/span> Taglio[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Materiale: <\/span> Ottone[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Rischi in caso di difetti:<\/span><\/p>\n<ul>\n<li>Azionamento impossibile<\/li>\n<li>Interruzione del movimento<\/li>\n<li>Impossibilit\u00e0 di montaggio<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_raw_html]PHRhYmxlPgogICAKICAgIDx0Ym9keT4KICAgICAgICA8dHI+CiAgICAgICAgICAgIDx0ZD5DUklURVJJIERJIFNFTEVaSU9ORTwvdGQ+CiAgICAgICAgICAgIDx0ZD5URUNOT0xPR0lBIFVUSUxJWlpBVEE8L3RkPgogICAgICAgIDwvdHI+CiAgICAgIDx0cj4KICAgICAgICAgICAgPHRkPkRpbWVuc2lvbmk8L3RkPgogICAgICAgICAgICA8dGQ+VmlzaW9uZSBhcnRpZmljaWFsZTwvdGQ+CiAgICAgICAgPC90cj4KICAgICAgPHRyPgogICAgICAgICAgICA8dGQ+Q29uZm9ybWl0w6AgZGVsbGEgZGVudGF0dXJhPC90ZD4KICAgICAgICAgICAgPHRkPlZpc2lvbmUgYXJ0aWZpY2lhbGU8L3RkPgogICAgICAgIDwvdHI+CiAgICAgCiAgICA8L3Rib2R5Pgo8L3RhYmxlPg==[\/vc_raw_html][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;border-radius-machine-tri range-vente-machine range-vente-machine-right block-invert&#8221; css=&#8221;.vc_custom_1662972406202{background-image: url(https:\/\/www.tqs-group.com\/wp-content\/uploads\/2022\/05\/degrade.jpg?id=449) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;txt-align-left-mobile&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<span class=\"txt-orange\">Tipo di pezzo:<\/span> Vite[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Processo di produzione:<\/span> Tornitura[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Materiale: <\/span> Acciaio[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Rischi in caso di difetti:<\/span><\/p>\n<ul>\n<li>Impossibilit\u00e0 di montaggio<\/li>\n<li>Danneggiamento della filettatura<\/li>\n<li>Estetica inaccettabile<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_raw_html]PHRhYmxlPgogICAKICAgIDx0Ym9keT4KICAgICAgICA8dHI+CiAgICAgICAgICAgIDx0ZD5DUklURVJJIERJIFNFTEVaSU9ORTwvdGQ+CiAgICAgICAgICAgIDx0ZD5URUNOT0xPR0lBIFVUSUxJWlpBVEE8L3RkPgogICAgICAgIDwvdHI+CiAgICAgIDx0cj4KICAgICAgICAgICAgPHRkPkRpbWVuc2lvbmk8L3RkPgogICAgICAgICAgICA8dGQ+VmlzaW9uZSBhcnRpZmljaWFsZTwvdGQ+CiAgICAgICAgPC90cj4KICAgICAgPHRyPgogICAgICAgICAgICA8dGQ+QXNwZXR0byBzdWxsYSB0ZXN0YTwvdGQ+CiAgICAgICAgICAgIDx0ZD5WaXNpb25lIGFydGlmaWNpYWxlPC90ZD4KICAgICAgICA8L3RyPgoKICAgICAgICAgPHRyPgogICAgICAgICAgICA8dGQ+RGlhbWV0cm8gZGVsbGEgZmlsZXR0YXR1cmEgc3UgMiBwcm9maWxpPC90ZD4KICAgICAgICAgICAgPHRkPlZpc2lvbmUgYXJ0aWZpY2lhbGU8L3RkPgogICAgICAgIDwvdHI+CiAgICAgCiAgICA8L3Rib2R5Pgo8L3RhYmxlPg==[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1919&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row el_class=&#8221;border-radius-machine-tri range-vente-machine range-vente-machine-left&#8221; css=&#8221;.vc_custom_1662972482279{background-image: url(https:\/\/www.tqs-group.com\/wp-content\/uploads\/2022\/05\/offre-pour-idustriel-installe.jpg?id=454) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1917&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<span class=\"txt-orange\">Tipo di pezzo:<\/span> Rondella[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Processo di produzione:<\/span> Tornitura[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Materiale: <\/span> Acciaio[\/vc_column_text][vc_separator color=&#8221;custom&#8221; align=&#8221;align_left&#8221; el_width=&#8221;40&#8243; accent_color=&#8221;#000000&#8243;][vc_column_text]<span class=\"txt-orange\">Rischi in caso di difetti:<\/span><\/p>\n<ul>\n<li>Impossibilit\u00e0 di montaggio<\/li>\n<li>Danneggiamento della filettatura<\/li>\n<li>Estetica inaccettabile<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_raw_html]PHRhYmxlPgogICAKICAgIDx0Ym9keT4KICAgICAgICA8dHI+CiAgICAgICAgICAgIDx0ZD5DUklURVJJIERJIFNFTEVaSU9ORTwvdGQ+CiAgICAgICAgICAgIDx0ZD5URUNOT0xPR0lBIFVUSUxJWlpBVEE8L3RkPgogICAgICAgIDwvdHI+CiAgICAgIDx0cj4KICAgICAgICAgICAgPHRkPkRpbWVuc2lvbmk8L3RkPgogICAgICAgICAgICA8dGQ+VmlzaW9uZSBhcnRpZmljaWFsZTwvdGQ+CiAgICAgICAgPC90cj4KICAgICAgPHRyPgogICAgICAgICAgICA8dGQ+QXNwZXR0byBzdWxsYSB0ZXN0YTwvdGQ+CiAgICAgICAgICAgIDx0ZD5WaXNpb25lIGFydGlmaWNpYWxlPC90ZD4KICAgICAgICA8L3RyPgoKICAgICAgICAgPHRyPgogICAgICAgICAgICA8dGQ+RGlhbWV0cm8gZGVsbGEgZmlsZXR0YXR1cmEgc3UgMiBwcm9maWxpPC90ZD4KICAgICAgICAgICAgPHRkPlZpc2lvbmUgYXJ0aWZpY2lhbGU8L3RkPgogICAgICAgIDwvdHI+CiAgICAgCiAgICA8L3Rib2R5Pgo8L3RhYmxlPg==[\/vc_raw_html][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][vc_btn title=&#8221;Contattaci!&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#0a0a0a&#8221; custom_text=&#8221;#f7941f&#8221; shape=&#8221;round&#8221; align=&#8221;left&#8221; link=&#8221;url:https%3A%2F%2Fwww.tqs-group.com%2Fit%2Fcontatti%2F|title:Contatti&#8221; el_class=&#8221;btn-black-orange&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_btn title=&#8221;Indietro&#8221; style=&#8221;custom&#8221; custom_background=&#8221;#f7941f&#8221; custom_text=&#8221;#ffffff&#8221; shape=&#8221;round&#8221; size=&#8221;xs&#8221; align=&#8221;left&#8221; i_icon_fontawesome=&#8221;fas fa-arrow-left&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.tqs-group.com%2Fit%2Fselezione-automatica-dei-pezzi%2F&#8221; el_class=&#8221;btn-orange-white&#8221;][vc_column_text]Il settore dell&#8217;orologeria \u00e8 composto da attori molto diversi tra loro che si rivolgono<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2813","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Selezione automatica dei pezzi nel settore dell&#039;orologeria, macchina di selezione automatica, ispezione dei pezzi per orologeria&lt;!--_<\/title>\n<meta name=\"description\" content=\"TQS offre il servizio di selezioneautomatica di pezzi per il settore dell&#039;orologeria, come i piedini a vite. Richiediun preventivo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selezione automatica dei pezzi nel settore dell&#039;orologeria, macchina di selezione automatica, ispezione dei pezzi per orologeria&lt;!--_\" \/>\n<meta property=\"og:description\" content=\"TQS offre il servizio di selezioneautomatica di pezzi per il settore dell&#039;orologeria, come i piedini a vite. Richiediun preventivo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/\" \/>\n<meta property=\"og:site_name\" content=\"Tri qualit\u00e9 service\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-14T11:20:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tqs-group.com\/wp-content\/uploads\/2022\/03\/tri-piece-usinage.png\" \/>\n\t<meta property=\"og:image:width\" content=\"385\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/selezione-automatica-pezzi-settore-orologeria\\\/\",\"url\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/selezione-automatica-pezzi-settore-orologeria\\\/\",\"name\":\"Selezione automatica dei pezzi nel settore dell'orologeria, macchina di selezione automatica, ispezione dei pezzi per orologeria&lt;!--_\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/#website\"},\"datePublished\":\"2022-05-23T10:01:40+00:00\",\"dateModified\":\"2023-02-14T11:20:58+00:00\",\"description\":\"TQS offre il servizio di selezioneautomatica di pezzi per il settore dell'orologeria, come i piedini a vite. Richiediun preventivo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/selezione-automatica-pezzi-settore-orologeria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/selezione-automatica-pezzi-settore-orologeria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/selezione-automatica-pezzi-settore-orologeria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selezione automatica dei pezzi per il settore dell&rsquo;orologeria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/\",\"name\":\"TRI QUALITE SERVICE\",\"description\":\"TQS Group\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/#organization\"},\"alternateName\":\"TQS GROUP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/#organization\",\"name\":\"TRI QUALITE SERVICE\",\"alternateName\":\"TQS GROUP\",\"url\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tqs-group.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/tri-piece-usinage.png\",\"contentUrl\":\"https:\\\/\\\/www.tqs-group.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/tri-piece-usinage.png\",\"width\":385,\"height\":380,\"caption\":\"TRI QUALITE SERVICE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tqs-group.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selezione automatica dei pezzi nel settore dell'orologeria, macchina di selezione automatica, ispezione dei pezzi per orologeria&lt;!--_","description":"TQS offre il servizio di selezioneautomatica di pezzi per il settore dell'orologeria, come i piedini a vite. Richiediun preventivo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/","og_locale":"it_IT","og_type":"article","og_title":"Selezione automatica dei pezzi nel settore dell'orologeria, macchina di selezione automatica, ispezione dei pezzi per orologeria&lt;!--_","og_description":"TQS offre il servizio di selezioneautomatica di pezzi per il settore dell'orologeria, come i piedini a vite. Richiediun preventivo!","og_url":"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/","og_site_name":"Tri qualit\u00e9 service","article_modified_time":"2023-02-14T11:20:58+00:00","og_image":[{"width":385,"height":380,"url":"https:\/\/www.tqs-group.com\/wp-content\/uploads\/2022\/03\/tri-piece-usinage.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/","url":"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/","name":"Selezione automatica dei pezzi nel settore dell'orologeria, macchina di selezione automatica, ispezione dei pezzi per orologeria&lt;!--_","isPartOf":{"@id":"https:\/\/www.tqs-group.com\/it\/#website"},"datePublished":"2022-05-23T10:01:40+00:00","dateModified":"2023-02-14T11:20:58+00:00","description":"TQS offre il servizio di selezioneautomatica di pezzi per il settore dell'orologeria, come i piedini a vite. Richiediun preventivo!","breadcrumb":{"@id":"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tqs-group.com\/it\/selezione-automatica-pezzi-settore-orologeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.tqs-group.com\/it\/"},{"@type":"ListItem","position":2,"name":"Selezione automatica dei pezzi per il settore dell&rsquo;orologeria"}]},{"@type":"WebSite","@id":"https:\/\/www.tqs-group.com\/it\/#website","url":"https:\/\/www.tqs-group.com\/it\/","name":"TRI QUALITE SERVICE","description":"TQS Group","publisher":{"@id":"https:\/\/www.tqs-group.com\/it\/#organization"},"alternateName":"TQS GROUP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tqs-group.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tqs-group.com\/it\/#organization","name":"TRI QUALITE SERVICE","alternateName":"TQS GROUP","url":"https:\/\/www.tqs-group.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tqs-group.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.tqs-group.com\/wp-content\/uploads\/2022\/03\/tri-piece-usinage.png","contentUrl":"https:\/\/www.tqs-group.com\/wp-content\/uploads\/2022\/03\/tri-piece-usinage.png","width":385,"height":380,"caption":"TRI QUALITE SERVICE"},"image":{"@id":"https:\/\/www.tqs-group.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.tqs-group.com\/it\/wp-json\/wp\/v2\/pages\/2813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tqs-group.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tqs-group.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tqs-group.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tqs-group.com\/it\/wp-json\/wp\/v2\/comments?post=2813"}],"version-history":[{"count":16,"href":"https:\/\/www.tqs-group.com\/it\/wp-json\/wp\/v2\/pages\/2813\/revisions"}],"predecessor-version":[{"id":3517,"href":"https:\/\/www.tqs-group.com\/it\/wp-json\/wp\/v2\/pages\/2813\/revisions\/3517"}],"wp:attachment":[{"href":"https:\/\/www.tqs-group.com\/it\/wp-json\/wp\/v2\/media?parent=2813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}